{"id":6477,"date":"2024-08-14T16:32:36","date_gmt":"2024-08-14T14:32:36","guid":{"rendered":"https:\/\/gfieurope.org\/it\/?p=6477"},"modified":"2024-08-07T16:35:22","modified_gmt":"2024-08-07T14:35:22","slug":"carne-coltivata-per-animali-domestici-la-prossima-novita-sostenibile-per-il-settore","status":"publish","type":"post","link":"https:\/\/gfieurope.org\/it\/blog\/carne-coltivata-per-animali-domestici-la-prossima-novita-sostenibile-per-il-settore\/","title":{"rendered":"Carne coltivata per animali domestici: la prossima novit\u00e0 sostenibile per il settore?"},"content":{"rendered":"<div class=\"page-header-side-image alignfull has-background has-gray-background-color\">\n\t\n\t<div class=\"page-header-side-image__wrap alignsemiwide\">\n\t\t\n\n<div class=\"page-header-side-image__content\">\n<h1 class=\"wp-block-heading\"><strong><strong><strong>Carne coltivata per animali domestici: la prossima novit\u00e0 sostenibile per il settore?<\/strong><\/strong><\/strong><span id=\"docs-internal-guid-2fdbcf28-7fff-1aa7-32bf-09b0c6bb8fbb\" style=\"font-weight:normal\"><div><span style=\"font-size: 11pt;font-family: Arial, sans-serif;background-color: transparent;font-weight: 700;vertical-align: baseline\"><\/span><\/div><\/span><span id=\"docs-internal-guid-36c8d49b-7fff-abad-4d78-49d6480327f2\" style=\"font-weight:normal\"><div><span style=\"font-size: 10.5pt;font-family: Arial, sans-serif;font-weight: 700;vertical-align: baseline\"><\/span><span style=\"font-size: 11pt;, sans-serif;background-color: transparent;font-weight: 700;vertical-align: baseline\"><\/span><\/div><\/span><\/h1>\n\n\n\n<p class=\"has-medium-font-size\">Il Regno Unito da il via libera all\u2019azienda Meatly per la produzione di <em>pet food<\/em> coltivato: esaminiamo i fattori alla base di questo nuovo settore e il suo rapporto con la carne coltivata per il consumo umano.<br><strong>\u00a0<\/strong><br><\/p>\n\n\n\n<p>14 agosto 2024<\/p>\n\n\n<div class=\"share\"><ul class=\"share__list\"><li class=\"share__item\"><a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fgfieurope.org%2Fit%2Fblog%2Fcarne-coltivata-per-animali-domestici-la-prossima-novita-sostenibile-per-il-settore%2F\" class=\"share__link share__link--facebook nls\" target=\"_blank\" rel=\"noopener\">\n\t<span class=\"a11y\">Condividi questa pagina su Facebook<\/span>\n\t<span class=\"share__icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"37\" height=\"37\" viewbox=\"0 0 37 37\" role=\"img\" focusable=\"false\" class=\"svg svg--facebook\"><path d=\"M37 18.613C37 8.333 28.717 0 18.5 0S0 8.333 0 18.613C0 27.903 6.765 35.603 15.61 37V23.993h-4.698v-5.38h4.697v-4.1c0-4.666 2.762-7.242 6.988-7.242 2.024 0 4.141.363 4.141.363v4.58h-2.332c-2.299 0-3.015 1.436-3.015 2.908v3.491h5.13l-.82 5.38h-4.31V37C30.235 35.604 37 27.903 37 18.613z\" fill-rule=\"nonzero\"><\/path><\/svg><!-- <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"24\" viewBox=\"0 0 263 448\"><path d=\"M239.75 3v66h-39.25c-30.75 0-36.5 14.75-36.5 36v47.25h73.25l-9.75 74h-63.5v189.75h-76.5v-189.75h-63.75v-74h63.75v-54.5c0-63.25 38.75-97.75 95.25-97.75 27 0 50.25 2 57 3z\"><\/path><\/svg> --><\/span>\n\t<span class=\"share__tooltip\" aria-hidden=\"true\">Share on Facebook<\/span>\n<\/a>\n<\/li><li class=\"share__item\"><a href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fgfieurope.org%2Fit%2Fblog%2Fcarne-coltivata-per-animali-domestici-la-prossima-novita-sostenibile-per-il-settore%2F\" class=\"share__link share__link--twitter nls\" target=\"_blank\" rel=\"noopener\">\n\t<span class=\"a11y\">Condividi questa pagina su Twitter<\/span>\n\t<span class=\"share__icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 512 512\" role=\"img\" focusable=\"false\" class=\"svg svg--twitter\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg><\/span>\n\t<span class=\"share__tooltip\" aria-hidden=\"true\">Share on X<\/span>\n<\/a>\n<\/li><li class=\"share__item\"><a href=\"https:\/\/www.linkedin.com\/shareArticle?url=https%3A%2F%2Fgfieurope.org%2Fit%2Fblog%2Fcarne-coltivata-per-animali-domestici-la-prossima-novita-sostenibile-per-il-settore%2F&amp;title=Carne%20coltivata%20per%20animali%20domestici%3A%20la%20prossima%20novit%C3%A0%20sostenibile%20per%20il%20settore%3F&amp;mini=true\" target=\"_blank\" rel=\"noopener\" class=\"share__link share__link--linkedin nls\">\n\t<span class=\"a11y\">Condividi questa pagina su LinkedIn<\/span>\n\t<span class=\"share__icon\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"33\" viewbox=\"0 0 32 33\" role=\"img\" focusable=\"false\" class=\"svg svg--linkedin\"><path d=\"M4 8c1.097 0 2.038-.392 2.823-1.177C7.608 6.016 8 5.075 8 4c0-1.086-.392-2.032-1.177-2.839C6.038.387 5.097 0 4 0 2.914 0 1.973.387 1.177 1.161.392 1.968 0 2.914 0 4c0 1.075.392 2.016 1.177 2.823C1.962 7.608 2.903 8 4 8zm13.41 24c.226 0 .42-.082.585-.247a.758.758 0 00.23-.555V20.406c0-1.397.272-2.492.815-3.283.533-.781 1.476-1.172 2.829-1.172 1.045 0 1.768.252 2.168.755.41.525.615 1.316.615 2.375v12.117c0 .216.076.401.23.555a.78.78 0 00.569.247h5.75c.205 0 .389-.082.553-.247a.768.768 0 00.246-.555V17.77c0-2.56-.738-4.496-2.214-5.812C28.321 10.653 26.281 10 23.668 10c-2.327 0-4.197.663-5.612 1.989 0-.113-.005-.231-.015-.355v-.17a2.536 2.536 0 01-.077-.4c-.051-.226-.128-.37-.23-.432-.113-.072-.272-.108-.477-.108h-5.458a.772.772 0 00-.568.231.776.776 0 00-.231.57v19.873c0 .216.077.401.23.555a.78.78 0 00.57.247h5.61zM6.227 33c.198 0 .377-.084.536-.253A.808.808 0 007 32.18V11.82a.826.826 0 00-.238-.584.711.711 0 00-.536-.237H.774a.711.711 0 00-.536.237.826.826 0 00-.238.584V32.18c0 .21.08.4.238.568.16.169.338.253.536.253h5.452z\" fill-rule=\"nonzero\"><\/path><\/svg><!-- <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" width=\"21\" height=\"24\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"\/><\/svg> --><\/span>\n\t<span class=\"share__tooltip\" aria-hidden=\"true\">Share on LinkedIn<\/span>\n<\/a>\n<\/li><\/ul><\/div><\/div>\n\n\n\n<div class=\"page-header-side-image__media\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-1024x683.jpg\" alt=\"cultivated pet food\" class=\"wp-image-6478\" style=\"aspect-ratio:4\/3;object-fit:cover\" srcset=\"https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-1024x683.jpg 1024w, https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-300x200.jpg 300w, https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-768x512.jpg 768w, https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-1536x1024.jpg 1536w, https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-2048x1365.jpg 2048w, https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-1620x1080.jpg 1620w, https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-437x291.jpg 437w, https:\/\/gfieurope.org\/it\/wp-content\/uploads\/sites\/3\/2024\/08\/gayatri-malhotra-4EqIO_yxqoU-unsplash-214x143.jpg 214w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\t<\/div>\n<\/div>\n\n\n\n<p>I cittadini europei amano gli animali. <a href=\"https:\/\/europeanpetfood.org\/wp-content\/uploads\/2024\/06\/FEDIAF-Facts-Figures-2022_Online100.pdf\" target=\"_blank\" rel=\"noopener\">Quasi la met\u00e0 di noi<\/a> ha accolto un animale da compagnia nella propria famiglia e nel 2022 abbiamo speso quasi 30 miliardi di euro in cibo per animali per mantenere in salute ottimale i nostri gatti, cani, conigli, uccelli e pesci. Sempre pi\u00f9 spesso <a href=\"https:\/\/www.petfoodindustry.com\/nutrition\/article\/15468431\/2022-pet-food-nutrition-trends-innovation-functionality\" target=\"_blank\" rel=\"noopener\">ricerchiamo marchi di cibo per animali di qualit\u00e0 superiore<\/a> con un contenuto di carne pi\u00f9 elevato, ma la tendenza a scegliere marchi premium pesa anche sull\u2019ambiente.&nbsp;<\/p>\n\n\n\n<p>Per questo motivo, alcune aziende stanno esplorando innovazioni alimentari come la carne coltivata, per sviluppare opzioni sostenibili di cibo per animali domestici: proprio in questo contesto, <a href=\"https:\/\/meatly.pet\/meatly-approval\/\" target=\"_blank\" rel=\"noopener\">la startup britannica Meatly ha ricevuto l&#8217;autorizzazione<\/a> a vendere il suo pollo coltivato per animali domestici nel Regno Unito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Il cibo per animali domestici \u00e8 sostenibile?<\/strong><\/h2>\n\n\n\n<p>Il nostro sistema alimentare, e in particolare i prodotti di origine animale come carne e latticini, hanno un impatto particolarmente elevato sull\u2019ambiente. L&#8217;allevamento di animali \u00e8 responsabile del <a href=\"https:\/\/www.nature.com\/articles\/s43016-021-00358-x\" target=\"_blank\" rel=\"noopener\">20% delle emissioni globali di gas serra<\/a>, pari a <a href=\"https:\/\/ourworldindata.org\/co2-emissions-from-transport\" target=\"_blank\" rel=\"noopener\">quelle <\/a>di tutti gli aerei, camion, automobili, treni e navi del mondo. La maggior parte della carne che produciamo \u00e8 destinata al consumo umano, ma <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0959378020307366\" target=\"_blank\" rel=\"noopener\">una quota significativa<\/a>, quasi la met\u00e0 dei 10,5 milioni di tonnellate di cibo per animali domestici venduto ogni anno in Europa, include carne e sottoprodotti animali come frattaglie e sangue. \u00c8 facile pensare che l&#8217;uso di sottoprodotti sia sostenibile, evitando sprechi; tuttavia, essi rappresentano una parte importante dei <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0959378020307366\" target=\"_blank\" rel=\"noopener\">profitti <\/a>dell&#8217;industria della carne e sono contesi anche da altri settori, come quello dei biocarburanti e dei fertilizzanti.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0959378020307366\" target=\"_blank\" rel=\"noopener\">Secondo una ricerca<\/a>, l&#8217;industria globale del cibo per animali domestici ha un impatto climatico paragonabile a quello di interi Paesi come le Filippine. I terreni agricoli utilizzati per produrre carne e altri ingredienti per alimenti per animali domestici coprono un&#8217;area doppia rispetto a quella del Regno Unito. E con la crescente domanda di prodotti premium, questi impatti potrebbero aumentare ulteriormente. Il cibo premium per animali domestici ha infatti un&#8217;impronta climatica 3,3 volte maggiore rispetto a quella del cibo per gatti standard e 2,3 volte maggiore rispetto a quella del cibo per cani di media qualit\u00e0. Per prevenire i peggiori effetti del cambiamento climatico, fermare la deforestazione e ripristinare gli habitat naturali, \u00e8 importante nutrire i nostri animali domestici in modo pi\u00f9 sostenibile. Tuttavia, molti proprietari di animali domestici non sono disposti a rinunciare a carne di pollo e tonno per i propri amici a quattro zampe. Per questo motivo, alcune aziende stanno guardando con interesse all\u2019agricoltura cellulare.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Che cos&#8217;\u00e8 il cibo per animali coltivato?<\/strong><\/h2>\n\n\n\n<p>La carne coltivata \u00e8 pensata per essere indistinguibile da quella di pollo, maiale, manzo e pesce che consumiamo oggi, ma viene prodotta in fermentatori anzich\u00e9 attraverso l&#8217;allevamento di animali. Il processo \u00e8 paragonabile alla coltivazione di piante da talea in una serra, che fornisce calore, terreno fertile, acqua e nutrienti. Si parte da un piccolo campione di cellule prelevato da un animale, che viene poi coltivato in un fermentatore, simile a quelli utilizzati per la produzione di birra. Questo ambiente controllato riproduce il processo naturale di crescita delle cellule, fornendo calore e nutrienti essenziali &#8211; come acqua, proteine, carboidrati, grassi, vitamine e minerali &#8211; per produrre carne in modo efficiente.<\/p>\n\n\n\n<p>Il risultato \u00e8 una carne macinata che pu\u00f2 essere trasformata in una variet\u00e0 di prodotti finali, indistinguibili dalla carne prodotta in modo convenzionale. Il cibo per animali domestici coltivato segue lo stesso processo, ma \u00e8 formulato specificamente per soddisfare le esigenze nutrizionali di cani e gatti. <a href=\"https:\/\/link.springer.com\/article\/10.1007\/s11367-022-02128-8\" target=\"_blank\" rel=\"noopener\">Studi peer-reviewed<\/a> indicano che la carne coltivata potrebbe ridurre le emissioni di gas serra fino al 92%, diminuire l&#8217;inquinamento atmosferico fino al 94% e utilizzare fino al 90% in meno di terra rispetto alla carne bovina tradizionale. Questa innovazione ha il potenziale di soddisfare la crescente domanda globale di carne senza aggiungere ulteriori pressioni sull&#8217;ambiente, contribuendo anche a rendere il cibo per animali domestici pi\u00f9 sostenibile.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>E il cibo per animali domestici a base vegetale?<\/strong><\/h2>\n\n\n\n<p>Accanto agli alimenti per animali domestici coltivati, anche le proteine vegetali e ottenute tramite fermentazione stanno entrando nel mercato, offrendo un&#8217;alimentazione completa con un impatto ambientale ridotto. Le ricerche sull&#8217;impatto del cibo per animali domestici completamente a base vegetale sui cani <a href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0265662\" target=\"_blank\" rel=\"noopener\">suggeriscono che<\/a>, rispetto al cibo convenzionale, i cani alimentati con diete vegetali tendono ad essere pi\u00f9 sani. I cani, essendosi evoluti insieme agli esseri umani, sono infatti in grado di <a href=\"https:\/\/www.nature.com\/articles\/nature11837#:~:text=Our%20results%20show%20that%20adaptations,step%20in%20early%20dog%20domestication.\" target=\"_blank\" rel=\"noopener\">adattarsi <\/a>a diete pi\u00f9 varie rispetto ai loro antenati.<\/p>\n\n\n\n<p>Tuttavia, questo adattamento non si applica a tutte le specie. La creazione di alimenti a base vegetale per carnivori puri, come i gatti, rappresenta una criticit\u00e0. In questo contesto, la carne coltivata e gli ingredienti come grassi e aminoacidi ottenuti tramite agricoltura cellulare, potrebbero migliorare le opzioni di cibo per animali domestici a base vegetale. Queste innovazioni offrono possibilit\u00e0 pi\u00f9 sostenibili e rispettose del benessere animale, contribuendo a massimizzare sia la salute dei nostri animali domestici sia quella del pianeta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qual \u00e8 la differenza tra il cibo coltivato per animali da compagnia e la carne coltivata per gli esseri umani?<\/strong><\/h2>\n\n\n\n<p>Mentre il gusto e la nutrizione sono fondamentali per il successo del cibo coltivato per animali da compagnia, la carne coltivata per gli esseri umani deve rispettare standard normativi molto pi\u00f9 rigorosi e richiede uno sviluppo del prodotto molto pi\u00f9 avanzato per conquistare chef, critici gastronomici e, naturalmente, consumatori. La carne coltivata \u00e8 gi\u00e0 stata approvata per la vendita a Singapore e negli Stati Uniti, ma per essere venduta in Europa, necessita dell&#8217;approvazione delle autorit\u00e0 regolatorie europee, un processo che includer\u00e0 una valutazione approfondita e basata su prove della sicurezza e del valore nutrizionale della carne coltivata, che durer\u00e0 almeno 18 mesi.<\/p>\n\n\n\n<p>Anche se l&#8217;Europa applica standard severi agli alimenti per animali domestici, il processo per portare questi prodotti sul mercato \u00e8 generalmente pi\u00f9 rapido. Pertanto, \u00e8 probabile che il cibo coltivato per cani e gatti arrivi sugli scaffali prima delle salsicce e delle bistecche coltivate per il consumo umano. Meatly, ad esempio, prevede di lanciare i primi campioni di cibo per animali domestici coltivati entro la fine di quest&#8217;anno. Pi\u00f9 scienziati e innovatori lavorano allo sviluppo della carne coltivata, pi\u00f9 velocemente il settore avanzer\u00e0, contribuendo positivamente all&#8217;industria alimentare in generale.<\/p>\n\n\n\n<p>Per fare in modo che la carne coltivata conquisti i palati umani e per sfruttare appieno i suoi benefici potenziali &#8211; dal miglioramento della sicurezza alimentare al supporto per l&#8217;agricoltura rigenerativa &#8211; sono essenziali investimenti pubblici e privati nella ricerca e nelle infrastrutture. Solo cos\u00ec sar\u00e0 possibile rendere la carne coltivata accessibile e conveniente per le persone in tutta Europa.<\/p>\n\n\n\n<div class=\"wp-block-buttons alignfull is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-black-color has-yellow-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/gfieurope.org\/it\/dona-ora\/\">Sostieni il nostro lavoro<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/gfieurope.org\/it\/ufficio-stampa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Contatta il nostro ufficio stampa<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Regno Unito da il via libera all\u2019azienda Meatly per la produzione di pet food coltivato: esaminiamo i fattori che stimolano questo nuovo settore e il suo rapporto con la carne coltivata per il consumo umano.<\/p>\n","protected":false},"author":12,"featured_media":6478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","external_url":"","footnotes":""},"categories":[35],"tags":[221,222,56],"authors":[],"production_platform":[197],"topic":[],"class_list":["post-6477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industria","tag-investimenti","tag-proteine-alternative","tag-european-union","production_platform-cross-pillar","has-blocks"],"acf":[],"_links":{"self":[{"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/posts\/6477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/comments?post=6477"}],"version-history":[{"count":2,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/posts\/6477\/revisions"}],"predecessor-version":[{"id":6481,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/posts\/6477\/revisions\/6481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/media\/6478"}],"wp:attachment":[{"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/media?parent=6477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/categories?post=6477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/tags?post=6477"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/authors?post=6477"},{"taxonomy":"production_platform","embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/production_platform?post=6477"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/gfieurope.org\/it\/wp-json\/wp\/v2\/topic?post=6477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}